{"id":5813,"date":"2025-01-03T16:20:22","date_gmt":"2025-01-03T16:20:22","guid":{"rendered":"https:\/\/sardasmeralda.com\/?post_type=properties_for_sale&#038;p=5813"},"modified":"2026-03-11T08:38:35","modified_gmt":"2026-03-11T08:38:35","slug":"wohnung-mit-garten-und-meerblick","status":"publish","type":"properties_for_sale","link":"https:\/\/sardasmeralda.com\/de\/properties-for-sale\/wohnung-mit-garten-und-meerblick\/","title":{"rendered":"APARTMENT MIT GARTEN UND MEERBLICK"},"content":{"rendered":"<p>Erdgeschosswohnung in der Residenz Gli Oleandri, Liscia di Vacca<\/p>\n<p>Diese neu renovierte Erdgeschosswohnung in der exklusiven Wohnanlage Gli Oleandri in Liscia di Vacca bietet modernen Komfort in einer der begehrtesten Lagen der Costa Smeralda. Mit einer Wohnfl\u00e4che von ca. 90 m\u00b2 ist sie ideal f\u00fcr Familien, Paare oder als stilvolle Ferienunterkunft.<\/p>\n<p>Ausstattung:<\/p>\n<p>2 Schlafzimmer, hell und ger\u00e4umig<br \/>\n2 moderne B\u00e4der, hochwertig renoviert<br \/>\nNeue K\u00fcche, komplett ausgestattet mit hochwertigen Ger\u00e4ten<br \/>\nPrivater Garten, perfekt f\u00fcr entspannte Stunden oder als Spielbereich f\u00fcr Kinder<\/p>\n<p>Die Residenz Gli Oleandri besticht durch ihre gepflegte Umgebung, einen Gemeinschaftspool und eine idyllische Atmosph\u00e4re. Der Strand ist bequem zu Fu\u00df erreichbar, sodass Sie die Sch\u00f6nheit des Mittelmeers in vollen Z\u00fcgen genie\u00dfen k\u00f6nnen.<\/p>\n<p>Eine perfekte Kombination aus Lage, Stil und Komfort \u2013 diese Immobilie ist ein wahres Juwel in der Costa Smeralda. Ideal sowohl als Erstwohnsitz als auch als Ferienwohnung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erdgeschosswohnung in der Residenz Gli Oleandri, Liscia di Vacca Diese neu renovierte Erdgeschosswohnung in der exklusiven Wohnanlage Gli Oleandri in Liscia di Vacca bietet modernen Komfort in einer der begehrtesten Lagen der Costa Smeralda. Mit einer Wohnfl\u00e4che von ca. 90 m\u00b2 ist sie ideal f\u00fcr Familien, Paare oder als stilvolle Ferienunterkunft. Ausstattung: 2 Schlafzimmer, hell und ger\u00e4umig 2 moderne B\u00e4der, hochwertig renoviert Neue K\u00fcche, komplett ausgestattet mit hochwertigen Ger\u00e4ten Privater Garten, perfekt f\u00fcr entspannte Stunden oder als Spielbereich f\u00fcr Kinder Die Residenz Gli Oleandri besticht durch ihre gepflegte Umgebung, einen Gemeinschaftspool und eine idyllische Atmosph\u00e4re. Der Strand ist bequem zu Fu\u00df erreichbar, sodass Sie die Sch\u00f6nheit des Mittelmeers in vollen Z\u00fcgen genie\u00dfen k\u00f6nnen. Eine perfekte Kombination aus Lage, Stil und Komfort \u2013 diese Immobilie ist ein wahres Juwel in der Costa Smeralda. Ideal sowohl als Erstwohnsitz als auch als Ferienwohnung.<\/p>\n","protected":false},"featured_media":9571,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-5813","properties_for_sale","type-properties_for_sale","status-publish","has-post-thumbnail","hentry","location-porto-cervo"],"acf":{"state_title":"Zustand","state":"Allgemein - In Bearbeitung","reference_title":"Referenz","reference":"85541015","price_title":"Preis","price":"550000","location_title":"Standort","location":"Hafen von Cervo","roomsandbedrooms_title":"Zimmer \/ Schlafzimmer","rooms__bedrooms":"3 Zimmer","usablesurface_title":"Nutzfl\u00e4che","usable_surface":"","standing_title":"Stehen","standing":"Wohnsiedlung","condition_title":"Zustand","condition":"Ausgezeichneter Zustand\/\u00fcberholt","exposure_title":"Belichtung","exposure":"Nordost","view_title":"Sicht","view":"Offen, Meer","availability_title":"Verf\u00fcgbarkeit","availability":"Frei","hotwater_title":"Hei\u00dfes Wasser","hot_water":"Privat","heating_title":"Heizung","heating":"Elektrisch, Klimaanlage, Autonom","floor_title":"Boden","floor":"Erdgeschoss","levels_title":"Ebenen","levels":"1","condominium_title":"","condominium_expenses":"","performance_title":"Leistung","performance":"Klimaanlage, M\u00f6bliert, Doppelverglasung, Grill, Gemeinschaftsgarten, Au\u00dfenbeleuchtung, Eingez\u00e4unt, Concierge, Swimmingpool.","proximity_title":"N\u00e4he","proximity":"Flughafen (25 km), Meer (5 Minuten), Arzt (3 km), Krankenhaus\/Klinik (3 km), Hafen (2 km), Strand (100 Meter), Supermarkt (2 km).","customlabels_title":"","custom_labels":"","regulation_title":"","regulation":[{"key":"BEE","value":"Available"}],"latitude_title":"Latitude","latitude":"41.13576","longitude_title":"Longitude","longitude":"9.51521","explore":"Erkunden","summary_title":"Zusammenfassung","discover_title":"Entdecken Sie weitere Immobilien","view_all_images_btn":"Alle Bilder anzeigen","hide_images_btn":"Bilder ausblenden","map_remove_text":"Die Kartenkoordinaten f\u00fcr diese Immobilie sind derzeit nicht verf\u00fcgbar.","property_gallery":[9571,9568,9586,9619,9565,9589,9574,9577,9580,9583,9592,9595,9598,9601,9604,9607,9625,9610,9613,9616,9622,9628],"featured_images_gallery":""},"_links":{"self":[{"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/properties_for_sale\/5813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/properties_for_sale"}],"about":[{"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/types\/properties_for_sale"}],"replies":[{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/comments?post=5813"}],"version-history":[{"count":8,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/properties_for_sale\/5813\/revisions"}],"predecessor-version":[{"id":20579,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/properties_for_sale\/5813\/revisions\/20579"}],"acf:attachment":[{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9628"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9622"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9616"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9613"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9610"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9625"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9607"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9604"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9601"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9598"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9595"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9592"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9583"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9580"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9577"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9574"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9589"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9565"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9619"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9586"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9568"},{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media\/9571"}],"wp:attachment":[{"href":"https:\/\/sardasmeralda.com\/de\/wp-json\/wp\/v2\/media?parent=5813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}